  {"id":10,"date":"2024-07-02T09:59:00","date_gmt":"2024-07-02T09:59:00","guid":{"rendered":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/?page_id=10"},"modified":"2024-09-27T15:03:26","modified_gmt":"2024-09-27T15:03:26","slug":"services","status":"publish","type":"page","link":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/services\/","title":{"rendered":"SERVICES"},"content":{"rendered":"\n<section class=\"wp-block-cover alignfull banner\" style=\"padding-top:18%;padding-bottom:18%;min-height:100%;aspect-ratio:unset;\" id=\"innerpagebanner\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#49494c\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"706\" class=\"wp-block-cover__image-background wp-image-160\" alt=\"servicebanner\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/servicebanner.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/servicebanner.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/servicebanner-300x110.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/servicebanner-1024x377.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/servicebanner-768x282.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/servicebanner-1536x565.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h1 class=\"wp-block-heading has-text-align-center h2 has-ast-global-color-5-color has-text-color has-link-color wp-elements-42a9d453bb84ff74f6fde2b595261c2a\" style=\"text-transform:uppercase\">SERVICES<\/h1>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-cover alignfull allsection\" style=\"padding-top:9%;padding-right:0px;padding-bottom:4%;padding-left:0px;min-height:100%;aspect-ratio:unset;\" id=\"providesection\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#041422\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1028\" class=\"wp-block-cover__image-background wp-image-163\" alt=\"Untitled-20\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20-300x161.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20-1024x548.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20-768x411.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20-1536x822.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-container-core-cover-is-layout-289edd49 wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns thirdsection  colreverse is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center weprovidecol companyheading is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-right:90px;padding-left:160px;flex-basis:52%\">\n<h2 class=\"wp-block-heading has-ast-global-color-5-color has-text-color has-link-color wp-elements-257693f0a5cbbe8ea526d449d12772a8\" style=\"padding-bottom:10px;text-transform:uppercase\">Brand <br>Strategy<\/h2>\n\n\n\n<p class=\"para has-ast-global-color-5-color has-text-color has-link-color wp-elements-18381a27e5b5010b3c15a7ed9efdbce3 wp-block-paragraph\" style=\"margin-bottom:50px;padding-right:200px\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.<\/p>\n\n\n\n<ul class=\"wp-block-list is-style-none has-ast-global-color-5-color has-text-color has-ast-global-color-5-color\">\n<li>Achieving effectiveness<\/li>\n\n\n\n<li>Perceiving and utilizing opportunities<\/li>\n\n\n\n<li>Mobilising resources<\/li>\n\n\n\n<li>Securing an advantageous position<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column image is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:48%\">\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"914\" height=\"920\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-211.png\" alt=\"Untitled-21(1)\" class=\"wp-image-164\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-211.png 914w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-211-298x300.png 298w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-211-150x150.png 150w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-211-768x773.png 768w\" sizes=\"auto, (max-width: 914px) 100vw, 914px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-cover alignfull allsection\" style=\"padding-top:9%;padding-right:0px;padding-bottom:4%;padding-left:0px;min-height:100%;aspect-ratio:unset;\" id=\"providesection\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#041422\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1044\" class=\"wp-block-cover__image-background wp-image-172\" alt=\"Untitled-24\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24-300x163.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24-1024x557.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24-768x418.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24-1536x835.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-container-core-cover-is-layout-289edd49 wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns thirdsection is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column image is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:48%\">\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"913\" height=\"920\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-25.png\" alt=\"Untitled-25\" class=\"wp-image-173\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-25.png 913w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-25-298x300.png 298w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-25-150x150.png 150w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-25-768x774.png 768w\" sizes=\"auto, (max-width: 913px) 100vw, 913px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center weprovidecol companyheading rightcol is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-left:300px;flex-basis:52%\">\n<h2 class=\"wp-block-heading has-ast-global-color-5-color has-text-color has-link-color wp-elements-395ab2cfe27f56868147b25e4009ceb7\" style=\"padding-bottom:10px;text-transform:uppercase\">App <br>Devlopment<\/h2>\n\n\n\n<p class=\"para has-ast-global-color-5-color has-text-color has-link-color wp-elements-e5f92e9f9358a0de09de6e51ce07b0d4 wp-block-paragraph\" style=\"margin-bottom:50px;padding-right:150px\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.<\/p>\n\n\n\n<ul class=\"wp-block-list is-style-checked has-ast-global-color-5-color has-text-color has-ast-global-color-5-color\">\n<li>Research beyond the business plan<\/li>\n\n\n\n<li>Marketing options and rates<\/li>\n\n\n\n<li>The ability to turnaround consulting<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-cover alignfull allsection\" style=\"padding-top:9%;padding-right:0px;padding-bottom:4%;padding-left:0px;min-height:100%;aspect-ratio:unset;\" id=\"providesection\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#041422\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1028\" class=\"wp-block-cover__image-background wp-image-163\" alt=\"Untitled-20\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20-300x161.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20-1024x548.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20-768x411.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-20-1536x822.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-container-core-cover-is-layout-289edd49 wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns thirdsection  colreverse is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center weprovidecol companyheading is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-right:90px;padding-left:160px;flex-basis:52%\">\n<h2 class=\"wp-block-heading has-ast-global-color-5-color has-text-color has-link-color wp-elements-cf5f043c8396d6f6bb280b2712eb0a30\" style=\"padding-bottom:10px;text-transform:uppercase\">UI\/UX <br>Design<\/h2>\n\n\n\n<p class=\"para has-ast-global-color-5-color has-text-color has-link-color wp-elements-18381a27e5b5010b3c15a7ed9efdbce3 wp-block-paragraph\" style=\"margin-bottom:50px;padding-right:200px\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.<\/p>\n\n\n\n<ul class=\"wp-block-list is-style-checked has-ast-global-color-5-color has-text-color has-ast-global-color-5-color\">\n<li>Achieving effectiveness<\/li>\n\n\n\n<li>Perceiving and utilizing opportunities<\/li>\n\n\n\n<li>Mobilising resources<\/li>\n\n\n\n<li>Securing an advantageous position<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column image is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:48%\">\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"914\" height=\"920\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-26.png\" alt=\"Untitled-26\" class=\"wp-image-174\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-26.png 914w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-26-298x300.png 298w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-26-150x150.png 150w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-26-768x773.png 768w\" sizes=\"auto, (max-width: 914px) 100vw, 914px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-cover alignfull allsection\" style=\"padding-top:9%;padding-right:0px;padding-bottom:10%;padding-left:0px;min-height:100%;aspect-ratio:unset;\" id=\"providesection\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#041422\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1044\" class=\"wp-block-cover__image-background wp-image-172\" alt=\"Untitled-24\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24-300x163.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24-1024x557.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24-768x418.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-24-1536x835.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-container-core-cover-is-layout-b22d6c07 wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns thirdsection is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column image is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:48%\">\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"913\" height=\"920\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-271.png\" alt=\"Untitled-27(1)\" class=\"wp-image-175\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-271.png 913w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-271-298x300.png 298w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-271-150x150.png 150w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-content\/uploads\/sites\/61\/2024\/07\/Untitled-271-768x774.png 768w\" sizes=\"auto, (max-width: 913px) 100vw, 913px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center weprovidecol companyheading rightcol is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-left:300px;flex-basis:52%\">\n<h2 class=\"wp-block-heading has-ast-global-color-5-color has-text-color has-link-color wp-elements-5cfe0e2b507676bbad1d18050b865ac3\" style=\"padding-bottom:10px;text-transform:uppercase\">visual <br>design<\/h2>\n\n\n\n<p class=\"para has-ast-global-color-5-color has-text-color has-link-color wp-elements-e5f92e9f9358a0de09de6e51ce07b0d4 wp-block-paragraph\" style=\"margin-bottom:50px;padding-right:150px\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.<\/p>\n\n\n\n<ul class=\"wp-block-list is-style-checked has-ast-global-color-5-color has-text-color has-ast-global-color-5-color\">\n<li>Research beyond the business plan<\/li>\n\n\n\n<li>Marketing options and rates<\/li>\n\n\n\n<li>The ability to turnaround consulting<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_eb_attr":"","_uag_custom_page_level_css":"","_editorskit_title_hidden":true,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Author","author_link":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/author\/soumya\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":1,"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":288,"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-json\/wp\/v2\/pages\/10\/revisions\/288"}],"wp:attachment":[{"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete5\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}