  {"id":11,"date":"2024-07-02T10:08:24","date_gmt":"2024-07-02T10:08:24","guid":{"rendered":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/?page_id=11"},"modified":"2024-07-17T19:00:03","modified_gmt":"2024-07-17T19:00:03","slug":"about-us","status":"publish","type":"page","link":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/about-us\/","title":{"rendered":"About Us"},"content":{"rendered":"\n<section class=\"wp-block-cover alignfull\" style=\"padding-top:20%;padding-bottom:19%;min-height:100%;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#5d5755\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"800\" class=\"wp-block-cover__image-background wp-image-131\" alt=\"about-banner\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-banner.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-banner.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-banner-300x125.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-banner-1024x427.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-banner-768x320.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-banner-1536x640.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<h1 class=\"wp-block-heading has-ast-global-color-5-color has-text-color has-link-color wp-elements-f36a1e38c6f15cf8c151489c34723b22\" style=\"margin-bottom:4%\">About Us<\/h1>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-cover alignfull is-light\" style=\"padding-top:6%;padding-bottom:6%;min-height:100%;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#fbf2ed\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1153\" class=\"wp-block-cover__image-background wp-image-60\" alt=\"about-bg\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-300x180.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-1024x615.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-768x461.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-1536x922.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:55%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"1020\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/img-1-min.png\" alt=\"img-1-min\" class=\"wp-image-62\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/img-1-min.png 870w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/img-1-min-256x300.png 256w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/img-1-min-768x900.png 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column blank is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:2%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center text-center is-layout-flow wp-block-column-is-layout-flow\">\n<h6 class=\"wp-block-heading has-ast-global-color-0-color has-text-color has-link-color wp-elements-664991cbf95152a2a8434ab612063fa0\">Our Story<\/h6>\n\n\n\n<h2 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-5fd91b36b317c9ca41dab7a5997f1530\" style=\"margin-bottom:5%\">Our Journey in<br>Web Design<\/h2>\n\n\n\n<p class=\"has-ast-global-color-1-color has-text-color has-link-color wp-elements-4051764e5ac52bee5240a48b86d7949f wp-block-paragraph\" style=\"font-size:18px\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Quis ipsum suspendisse ultrices gravida. Risus commodo viverra maecenas accumsan lacus vel facilisis.<\/p>\n\n\n\n<p class=\"has-ast-global-color-1-color has-text-color has-link-color wp-elements-2321593810c17af00de50b167fbd0c58 wp-block-paragraph\" style=\"margin-bottom:0;font-size:18px\">Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam, eaque ipsa quae ab illo inventore veritatis et quasi architecto beatae vitae dicta sunt explicabo. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia consequuntur magni dolores eos qui ratione voluptatem sequi nesciunt. Neque porro quisquam est, qui dolorem ipsum quia dolor sit amet.<\/p>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-cover alignfull is-light\" style=\"padding-top:6%;padding-bottom:6%;min-height:100%;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#fbf2ed\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1153\" class=\"wp-block-cover__image-background wp-image-60\" alt=\"about-bg\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-300x180.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-1024x615.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-768x461.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-1536x922.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<h6 class=\"wp-block-heading has-text-align-center has-ast-global-color-0-color has-text-color has-link-color wp-elements-8b253fc211bf56989233981815d22b53\">Our Story<\/h6>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-ast-global-color-4-color has-text-color has-link-color wp-elements-bf487f92f418c08d7c352dad67e3e136\">Our Streamlined Design Process<\/h2>\n\n\n\n<p class=\"has-text-align-center p-br has-ast-global-color-1-color has-text-color has-link-color wp-elements-d328e82a7cd5a925b637d6b7d228d28e wp-block-paragraph\" style=\"margin-bottom:5%;font-size:18px\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et <br>dolore magna aliqua. Quis ipsum suspendisse ultrices gravida.<\/p>\n\n\n\n<div class=\"wp-block-columns wrap is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col-48 is-layout-flow wp-block-column-is-layout-flow\">\n<h5 class=\"wp-block-heading has-ast-global-color-1-color has-text-color has-link-color wp-elements-70d9622b3dd665fd0b5ae8c72cfb6ce1\" style=\"font-style:normal;font-weight:400\">Step 1 <img decoding=\"async\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/line.png\"><\/h5>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"58\" height=\"70\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/disco.png\" alt=\"disco\" class=\"wp-image-151\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-9ef0130460354b7459d2ec5f80a53bf9\" style=\"margin-top:30px;margin-bottom:10px\">Discover<\/h4>\n\n\n\n<p class=\"has-ast-global-color-1-color has-text-color has-link-color wp-elements-47dfefd92ad4bc73d75b872a635d0e8f wp-block-paragraph\" style=\"margin-bottom:0\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column col-48 is-layout-flow wp-block-column-is-layout-flow\">\n<h5 class=\"wp-block-heading has-ast-global-color-1-color has-text-color has-link-color wp-elements-2380c04daa80e6e7508cfeb09bb525e4\" style=\"font-style:normal;font-weight:400\">Step 2 <img decoding=\"async\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/line.png\"><\/h5>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"77\" height=\"70\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/graphic_design.png\" alt=\"graphic_design\" class=\"wp-image-152\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-476060cd8ea70e6df0d97db1673bd70b\" style=\"margin-top:30px;margin-bottom:10px\">Define &amp; Design<\/h4>\n\n\n\n<p class=\"has-ast-global-color-1-color has-text-color has-link-color wp-elements-47dfefd92ad4bc73d75b872a635d0e8f wp-block-paragraph\" style=\"margin-bottom:0\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column col-48 is-layout-flow wp-block-column-is-layout-flow\">\n<h5 class=\"wp-block-heading has-ast-global-color-1-color has-text-color has-link-color wp-elements-612871a8bf1bda46295cb1091bbe9754\" style=\"font-style:normal;font-weight:400\">Step 3 <img decoding=\"async\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/line.png\"><\/h5>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/software.png\" alt=\"software\" class=\"wp-image-146\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-5ccdeb7f10038f81fddaf762b455d864\" style=\"margin-top:28px;margin-bottom:10px\">Develop<\/h4>\n\n\n\n<p class=\"has-ast-global-color-1-color has-text-color has-link-color wp-elements-47dfefd92ad4bc73d75b872a635d0e8f wp-block-paragraph\" style=\"margin-bottom:0\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column col-48 is-layout-flow wp-block-column-is-layout-flow\">\n<h5 class=\"wp-block-heading has-ast-global-color-1-color has-text-color has-link-color wp-elements-1042670433268377420402a99f634610\" style=\"font-style:normal;font-weight:400\">Step 4 <img decoding=\"async\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/line.png\"><\/h5>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/startup.png\" alt=\"startup\" class=\"wp-image-147\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-8529ba2cc0d3cb7d900df7d9d75276fa\" style=\"margin-top:30px;margin-bottom:10px\">Deliver<\/h4>\n\n\n\n<p class=\"has-ast-global-color-1-color has-text-color has-link-color wp-elements-47dfefd92ad4bc73d75b872a635d0e8f wp-block-paragraph\" style=\"margin-bottom:0\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore.<\/p>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-cover alignfull is-light\" style=\"padding-top:6%;padding-bottom:6%;min-height:100%;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-ast-global-color-7-background-color has-background-dim-0 has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1153\" class=\"wp-block-cover__image-background wp-image-60\" alt=\"about-bg\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-300x180.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-1024x615.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-768x461.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-1536x922.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-stackable-video-popup stk-block-video-popup stk-block stk-4d33fa1\" data-video=\"https:\/\/youtu.be\/u31qwQUeGuM\" data-block-id=\"4d33fa1\"><style>.stk-4d33fa1{margin-bottom:0px !important}<\/style><div class=\"stk-block-video-popup__overlay stk-row stk-inner-blocks stk-block-content stk-hover-parent\" aria-label=\"Play Video\" tabindex=\"0\" role=\"button\">\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-center stk-block stk-cd8b61a\" data-block-id=\"cd8b61a\"><style>.stk-cd8b61a{border-top-left-radius:3px !important;border-top-right-radius:3px !important;border-bottom-right-radius:3px !important;border-bottom-left-radius:3px !important;overflow:hidden !important}.stk-cd8b61a .stk--svg-wrapper .stk--inner-svg svg:last-child,.stk-cd8b61a .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g,path,rect,polygon,ellipse){fill:#00000000 !important}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-cd8b61a\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-cd-8-b-61-a-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-cd-8-b-61-a-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg data-prefix=\"fas\" data-icon=\"play\" class=\"svg-inline--fa fa-play fa-w-14\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-6bbe512\" data-block-id=\"6bbe512\"><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-140\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/video.png\" width=\"1600\" height=\"750\" alt=\"about-banner\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/video.png 1600w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/video-300x141.png 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/video-1024x480.png 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/video-768x360.png 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/video-1536x720.png 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/span><\/figure><\/div>\n<\/div><\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-cover alignfull is-light\" style=\"padding-top:6%;padding-bottom:6%;min-height:100%;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#fbf2ed\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1153\" class=\"wp-block-cover__image-background wp-image-60\" alt=\"about-bg\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-300x180.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-1024x615.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-768x461.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-1536x922.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center text-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:45%\">\n<h6 class=\"wp-block-heading has-ast-global-color-0-color has-text-color has-link-color wp-elements-fa9a115a1a91a0a54395f8378eb6c593\">Why Choose Us<\/h6>\n\n\n\n<h2 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-29d6486355fe700f97eb78395d5ad447\" style=\"margin-bottom:5%\">The Benefits of<br>Partnering with Us<\/h2>\n\n\n\n<p class=\"has-ast-global-color-1-color has-text-color has-link-color wp-elements-4051764e5ac52bee5240a48b86d7949f wp-block-paragraph\" style=\"font-size:18px\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Quis ipsum suspendisse ultrices gravida. Risus commodo viverra maecenas accumsan lacus vel facilisis.<\/p>\n\n\n\n<p class=\"has-ast-global-color-1-color has-text-color has-link-color wp-elements-f6495317dc7925e35a928db8ebe8d6f7 wp-block-paragraph\" style=\"font-size:18px\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.<\/p>\n\n\n\n<ul style=\"padding-left:30px;font-size:20px;font-style:normal;font-weight:600;line-height:1\" class=\"wp-block-list tick has-ast-global-color-0-color has-text-color has-ast-global-color-0-color\">\n<li style=\"margin-bottom:20px\">  Lorem Ipsum Dolor Sit Amet.<\/li>\n\n\n\n<li style=\"margin-bottom:20px\">  Quis Ipsum Suspendise Ultrices Gravida.<\/li>\n\n\n\n<li>  Sed Do Eiusmod Tempor Incididunt Ut Labore.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:55%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"1020\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/img-3-min.png\" alt=\"img-3-min\" class=\"wp-image-137\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/img-3-min.png 870w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/img-3-min-256x300.png 256w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/img-3-min-768x900.png 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-cover alignfull is-light\" style=\"padding-top:6%;padding-bottom:6%;min-height:100%;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#fbf2ed\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1153\" class=\"wp-block-cover__image-background wp-image-60\" alt=\"about-bg\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-300x180.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-1024x615.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-768x461.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/about-bg-1536x922.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column text-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:53%\">\n<h6 class=\"wp-block-heading has-ast-global-color-0-color has-text-color has-link-color wp-elements-1e3041cc45ad09ff687ef9bbec040edf\">Our Team<\/h6>\n\n\n\n<h2 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-8ea829d788c5ef978f697dec8a25ee8b\" style=\"margin-bottom:5%\">Meet Our Expert Team<br>Members<\/h2>\n\n\n\n<p class=\"has-ast-global-color-1-color has-text-color has-link-color wp-elements-c03f30c253e0a5ff6f7fd92d2ded5bfa wp-block-paragraph\" style=\"margin-bottom:0;padding-right:10%;font-size:18px\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Quis ipsum suspendisse ultrices gravida. Risus commodo viverra maecenas accumsan lacus vel facilisis.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-stackable-carousel alignfull stk-block-carousel stk--is-slide stk--infinite-scroll stk--arrows-outside stk--arrows-justify-flex-end stk--arrows-align-flex-start stk-block stk-b6c85c3\" data-slides-to-show=\"3\" data-block-id=\"b6c85c3\"><style>.stk-b6c85c3{margin-bottom:0px !important;--slides-to-show:3 !important;--button-width:70px !important;--button-height:70px !important}.stk-b6c85c3 .stk-block-carousel__buttons{justify-content:flex-end !important}.stk-b6c85c3 .stk-block-carousel__button{background:var(--ast-global-color-3) !important;fill:var(--ast-global-color-0) !important;opacity:1 !important}.stk-b6c85c3 .stk-block-carousel__button:hover{background:var(--ast-global-color-0) !important;fill:var(--ast-global-color-5) !important}.stk-b6c85c3 .stk-block-carousel__button svg.ugb-custom-icon :is(g,path,rect,polygon,ellipse){fill:var(--ast-global-color-0) !important}.stk-b6c85c3 .stk-block-carousel__button svg.ugb-custom-icon :is(g,path,rect,polygon,ellipse):hover{fill:var(--ast-global-color-5) !important}@media screen and (max-width:1023px){.stk-b6c85c3{--slides-to-show:2 !important;--gap:20px !important;--button-width:50px !important;--button-height:50px !important}}@media screen and (max-width:767px){.stk-b6c85c3{--slides-to-show:1 !important}}<\/style><div class=\"stk-block-carousel__content-wrapper\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-block-carousel__slider-wrapper stk-content-align stk-b6c85c3-column alignfull\"><div class=\"stk-block-carousel__slider\" role=\"list\" data-autoplay=\"4000\" data-label-slide-of=\"Slide %%d of %%d\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-6414650\" data-v=\"4\" data-block-id=\"6414650\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-6414650-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-6414650-inner-blocks\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column service-hover is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image alignfull size-full caption-align-center service-img\"><img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"700\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/ethan-min.png\" alt=\"ethan-min\" class=\"wp-image-135\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/ethan-min.png 516w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/ethan-min-221x300.png 221w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><figcaption class=\"wp-element-caption\"><h3><span style=\"color: var(--ast-global-color-5);\" class=\"stk-highlight\">Ethan Davis<\/span><\/h3><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-columns hover-content is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-right:10%;padding-left:10%\">\n<h3 class=\"wp-block-heading has-text-align-center has-ast-global-color-5-color has-text-color has-link-color wp-elements-931f859757815da35fa01e9f7484eb57\">Ethan Davis<\/h3>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-center has-ast-global-color-0-color has-text-color has-link-color wp-elements-a07c318fe5801814665a13dfc15243d2\" style=\"text-transform:capitalize\">Senior Designer<\/h6>\n\n\n\n<div class=\"wp-block-essential-blocks-social  root-eb-social-links-1e3gu\"><div class=\"eb-parent-wrapper eb-parent-eb-social-links-1e3gu \"><div class=\"eb-social-links-1e3gu eb-social-links-wrapper\"><ul class=\"eb-socials\"><li><a class=\"x-twitter-original  \" href=\"\" target=\"_self\" rel=\"noopener\" aria-label=\"social link\"><i class=\"hvr-icon eb-social-icon fab fa-x-twitter\"><\/i><\/a><\/li><li><a class=\"facebook-f-original  \" href=\"\" target=\"_self\" rel=\"noopener\" aria-label=\"social link\"><i class=\"hvr-icon eb-social-icon fab fa-facebook-f\"><\/i><\/a><\/li><li><a class=\"instagram-original  \" href=\"\" target=\"_self\" rel=\"noopener\" aria-label=\"social link\"><i class=\"hvr-icon eb-social-icon fab fa-instagram\"><\/i><\/a><\/li><\/ul><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ab461\" data-v=\"4\" data-block-id=\"53ab461\"><style>@media screen and (max-width:767px){.stk-53ab461{margin-top:0px !important}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ab461-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ab461-inner-blocks\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column service-hover is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image alignfull size-full caption-align-center service-img\"><img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"700\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/emily-min.png\" alt=\"emily-min\" class=\"wp-image-134\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/emily-min.png 516w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/emily-min-221x300.png 221w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><figcaption class=\"wp-element-caption\"><h3><span style=\"color: var(--ast-global-color-5);\" class=\"stk-highlight\">Emily Johnson<\/span><\/h3><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-columns hover-content is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-right:10%;padding-left:10%\">\n<h3 class=\"wp-block-heading has-text-align-center has-ast-global-color-5-color has-text-color has-link-color wp-elements-356805ecbdf629302ef9266e91645e82\">Emily Johnson<\/h3>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-center has-ast-global-color-0-color has-text-color has-link-color wp-elements-a07c318fe5801814665a13dfc15243d2\" style=\"text-transform:capitalize\">Senior Designer<\/h6>\n\n\n\n<div class=\"wp-block-essential-blocks-social  root-eb-social-links-0gfwk\"><div class=\"eb-parent-wrapper eb-parent-eb-social-links-0gfwk \"><div class=\"eb-social-links-0gfwk eb-social-links-wrapper\"><ul class=\"eb-socials\"><li><a class=\"x-twitter-original  \" href=\"\" target=\"_self\" rel=\"noopener\" aria-label=\"social link\"><i class=\"hvr-icon eb-social-icon fab fa-x-twitter\"><\/i><\/a><\/li><li><a class=\"facebook-f-original  \" href=\"\" target=\"_self\" rel=\"noopener\" aria-label=\"social link\"><i class=\"hvr-icon eb-social-icon fab fa-facebook-f\"><\/i><\/a><\/li><li><a class=\"instagram-original  \" href=\"\" target=\"_self\" rel=\"noopener\" aria-label=\"social link\"><i class=\"hvr-icon eb-social-icon fab fa-instagram\"><\/i><\/a><\/li><\/ul><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-6b4e61e\" data-v=\"4\" data-block-id=\"6b4e61e\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-6b4e61e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-6b4e61e-inner-blocks\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column service-hover is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image alignfull size-full caption-align-center service-img\"><img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"700\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/jannie-min.png\" alt=\"jannie-min\" class=\"wp-image-136\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/jannie-min.png 516w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/jannie-min-221x300.png 221w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><figcaption class=\"wp-element-caption\"><h3><span style=\"color: var(--ast-global-color-5);\" class=\"stk-highlight\">Jannie Park<\/span><\/h3><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-columns hover-content is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-right:10%;padding-left:10%\">\n<h3 class=\"wp-block-heading has-text-align-center has-ast-global-color-5-color has-text-color has-link-color wp-elements-7b57abb61bbdcc343e5332cb05873b1e\">Jannie Park<\/h3>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-center has-ast-global-color-0-color has-text-color has-link-color wp-elements-a07c318fe5801814665a13dfc15243d2\" style=\"text-transform:capitalize\">Senior Designer<\/h6>\n\n\n\n<div class=\"wp-block-essential-blocks-social  root-eb-social-links-0swu7\"><div class=\"eb-parent-wrapper eb-parent-eb-social-links-0swu7 \"><div class=\"eb-social-links-0swu7 eb-social-links-wrapper\"><ul class=\"eb-socials\"><li><a class=\"x-twitter-original  \" href=\"\" target=\"_self\" rel=\"noopener\" aria-label=\"social link\"><i class=\"hvr-icon eb-social-icon fab fa-x-twitter\"><\/i><\/a><\/li><li><a class=\"facebook-f-original  \" href=\"\" target=\"_self\" rel=\"noopener\" aria-label=\"social link\"><i class=\"hvr-icon eb-social-icon fab fa-facebook-f\"><\/i><\/a><\/li><li><a class=\"instagram-original  \" href=\"\" target=\"_self\" rel=\"noopener\" aria-label=\"social link\"><i class=\"hvr-icon eb-social-icon fab fa-instagram\"><\/i><\/a><\/li><\/ul><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/div><div class=\"stk-block-carousel__buttons\"><button class=\"stk-block-carousel__button stk-block-carousel__button__prev\" aria-label=\"Previous slide\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M9.4 233.4c-12.5 12.5-12.5 32.8 0 45.3l160 160c12.5 12.5 32.8 12.5 45.3 0s12.5-32.8 0-45.3L109.2 288 416 288c17.7 0 32-14.3 32-32s-14.3-32-32-32l-306.7 0L214.6 118.6c12.5-12.5 12.5-32.8 0-45.3s-32.8-12.5-45.3 0l-160 160z\"><\/path><\/svg><\/button><button class=\"stk-block-carousel__button stk-block-carousel__button__next\" aria-label=\"Next slide\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M438.6 278.6c12.5-12.5 12.5-32.8 0-45.3l-160-160c-12.5-12.5-32.8-12.5-45.3 0s-12.5 32.8 0 45.3L338.8 224 32 224c-17.7 0-32 14.3-32 32s14.3 32 32 32l306.7 0L233.4 393.4c-12.5 12.5-12.5 32.8 0 45.3s32.8 12.5 45.3 0l160-160z\"><\/path><\/svg><\/button><\/div><\/div><\/div><\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-cover alignfull is-light full-width\" style=\"padding-top:2%;padding-right:0px;padding-bottom:10%;padding-left:0px;min-height:100%;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#fbf2ec\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"804\" class=\"wp-block-cover__image-background wp-image-119\" alt=\"gallery-bg\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/gallery-bg.jpg\" style=\"object-position:50% 100%\" data-object-fit=\"cover\" data-object-position=\"50% 100%\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/gallery-bg.jpg 1920w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/gallery-bg-300x126.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/gallery-bg-1024x429.jpg 1024w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/gallery-bg-768x322.jpg 768w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/gallery-bg-1536x643.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-container-core-cover-is-layout-2d118e37 wp-block-cover-is-layout-constrained\">\n<h6 class=\"wp-block-heading has-text-align-center has-ast-global-color-0-color has-text-color has-link-color wp-elements-90e65b3ed11bf9fe3015aa369aa0cb70\">Gallery<\/h6>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-ast-global-color-4-color has-text-color has-link-color wp-elements-c84c8776111bb37bcfed95a2a28a0b51\" style=\"margin-bottom:4%\">Follow Us on Istagram<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-5 wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"384\" height=\"384\" data-id=\"120\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-1.jpg\" alt=\"g-1\" class=\"wp-image-120\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-1.jpg 384w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-1-300x300.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"384\" height=\"384\" data-id=\"121\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-2.jpg\" alt=\"g-2\" class=\"wp-image-121\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-2.jpg 384w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-2-300x300.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-2-150x150.jpg 150w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"384\" height=\"384\" data-id=\"122\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-3.jpg\" alt=\"g-3\" class=\"wp-image-122\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-3.jpg 384w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-3-300x300.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-3-150x150.jpg 150w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"384\" height=\"384\" data-id=\"123\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-4.jpg\" alt=\"g-4\" class=\"wp-image-123\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-4.jpg 384w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-4-300x300.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-4-150x150.jpg 150w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"384\" height=\"384\" data-id=\"124\" src=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-5.jpg\" alt=\"g-5\" class=\"wp-image-124\" srcset=\"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-5.jpg 384w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-5-300x300.jpg 300w, https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-content\/uploads\/sites\/63\/2024\/07\/g-5-150x150.jpg 150w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/figure>\n<\/figure>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_eb_attr":"","_uag_custom_page_level_css":"","_editorskit_title_hidden":true,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry"],"acf":[],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":""},"post_excerpt_stackable_v2":"<p>About Us Our Story Our Journey inWeb Design Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Quis ipsum suspendisse ultrices gravida. Risus commodo viverra maecenas accumsan lacus vel facilisis. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam, eaque ipsa quae ab illo inventore veritatis et quasi architecto beatae vitae dicta sunt explicabo. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia consequuntur magni dolores eos qui ratione voluptatem sequi nesciunt. Neque porro quisquam est, qui dolorem&hellip;<\/p>\n","category_list_v2":"","author_info_v2":{"name":"Deesha Bishu","url":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/author\/deesha\/"},"comments_num_v2":"0 comments","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Deesha Bishu","author_link":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/author\/deesha\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":0,"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"wp:attachment":[{"href":"https:\/\/pixelpartnerdigital.com\/web-design-and-development-templete7\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}